{"id":3758,"date":"2018-10-22T20:34:48","date_gmt":"2018-10-22T18:34:48","guid":{"rendered":"http:\/\/clubcorvette.se\/sydost\/?p=3758"},"modified":"2018-10-22T20:34:48","modified_gmt":"2018-10-22T18:34:48","slug":"hostmote-karlskrona","status":"publish","type":"post","link":"https:\/\/clubcorvette.se\/sydost\/hostmote-karlskrona\/","title":{"rendered":"H\u00f6stm\u00f6te Karlskrona"},"content":{"rendered":"<p><a name=\"_GoBack\"><\/a><span style=\"color: #000000;font-family: Calibri\">H\u00d6STM\u00d6TE KARLSKRONA<\/span><\/p>\n<p><span style=\"color: #000000;font-family: Calibri\">F\u00f6rsta stopp f\u00f6r denna dag blev p\u00e5 Marinmuseet i Karlskrona, d\u00e4r fick vi en intressant guide tur med Rolf och Rolf.<\/span><\/p>\n<p><span style=\"color: #000000;font-family: Calibri\">Det blev en runda p\u00e5 ub\u00e5ts biten sedan lite historik om Karlskrona och marinen. Tror ni inte v\u00e5r egna president(Sandin) har haft tj\u00e4nsteg\u00f6rning p\u00e5 ub\u00e5ten Neptun eller var det Hajen Mmm.. lite oklart.<\/span><\/p>\n<p><span style=\"color: #000000;font-family: Calibri\">\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;font-family: Calibri\">N\u00e4sta stopp var hos TopClass bilrekond d\u00e4r vi kikade p\u00e5 hans nya lokaler, det blev \u00e4ven lite f\u00f6r magen och en tipsrunda(kanske inte allt f\u00f6r sv\u00e5r s\u00e5 det var tur vi hade utslagsfr\u00e5ga Haha). \u00c4r ni sugna p\u00e5 att putsa till era bilar s\u00e5 l\u00e4mnar Carl-Martin 10% p\u00e5 Club bilar, bra va!!<\/span><\/p>\n<p><span style=\"color: #000000;font-family: Calibri\">S\u00e5 efter TopClass var det dags f\u00f6r en k\u00f6rrunda i det underbara sensommar v\u00e4dret, efter 1,5tim njutbar bilk\u00f6rning landade vi p\u00e5 Niklastorps Golf restaurang.<\/span><\/p>\n<p><span style=\"color: #000000;font-family: Calibri\">D\u00e4r blev vi mottagna av Sofia som hade dukat upp en underbar buff\u00e9, till allas uppskattning s\u00e5 blev det en fantastisk god t\u00e5rta till kaffet.<\/span><\/p>\n<p><span style=\"color: #000000;font-family: Calibri\">Detta var allt f\u00f6r oss vi v\u00e4ljer nu att l\u00e4mna \u00f6ver stafett pinnen till n\u00e5gon annan i distriktet.<\/span><\/p>\n<p><span style=\"color: #000000;font-family: Calibri\">Lasse &amp; Petra<\/span><\/p>\n<p><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095315.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3695\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095315-300x225.jpg\" alt=\"20180908_095315\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095315-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095315-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095315.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095315-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_094606.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3693\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_094606-300x225.jpg\" alt=\"20180908_094606\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_094606-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_094606-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_094606.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_094606-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_093817.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3691\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_093817-300x225.jpg\" alt=\"20180908_093817\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_093817-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_093817-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_093817.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_093817-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095320.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3696\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095320-300x225.jpg\" alt=\"20180908_095320\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095320-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095320-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095320.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095320-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095353.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3699\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095353-300x225.jpg\" alt=\"20180908_095353\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095353-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095353-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095353.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095353-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095337.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3698\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095337-300x225.jpg\" alt=\"20180908_095337\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095337-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095337-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095337.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095337-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095335.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3697\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095335-300x225.jpg\" alt=\"20180908_095335\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095335-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095335-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095335.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_095335-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_101521.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3703\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_101521-225x300.jpg\" alt=\"20180908_101521\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_101521-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_101521-480x640.jpg 480w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_101521.jpg 576w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_104647.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3705\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_104647-225x300.jpg\" alt=\"20180908_104647\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_104647-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_104647-480x640.jpg 480w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_104647.jpg 576w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_101608.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3704\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_101608-225x300.jpg\" alt=\"20180908_101608\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_101608-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_101608-480x640.jpg 480w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_101608.jpg 576w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_105005.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3708\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_105005-225x300.jpg\" alt=\"20180908_105005\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_105005-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_105005-480x640.jpg 480w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_105005.jpg 576w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_104700.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3707\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_104700-225x300.jpg\" alt=\"20180908_104700\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_104700-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_104700-480x640.jpg 480w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_104700.jpg 576w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_104651.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3706\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_104651-225x300.jpg\" alt=\"20180908_104651\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_104651-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_104651-480x640.jpg 480w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_104651.jpg 576w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_110540.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3709\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_110540-225x300.jpg\" alt=\"20180908_110540\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_110540-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_110540-480x640.jpg 480w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_110540.jpg 576w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114813.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3711\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114813-225x300.jpg\" alt=\"20180908_114813\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114813-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114813-480x640.jpg 480w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114813.jpg 576w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114820.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3713\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114820-225x300.jpg\" alt=\"20180908_114820\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114820-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114820-480x640.jpg 480w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114820.jpg 576w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_115614.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3715\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_115614-300x225.jpg\" alt=\"20180908_115614\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_115614-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_115614-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_115614.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_115614-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114844.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3714\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114844-300x225.jpg\" alt=\"20180908_114844\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114844-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114844-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114844.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/09\/20180908_114844-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123706.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3770\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123706-300x225.jpg\" alt=\"20180908_123706\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123706-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123706-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123706.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123706-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123651.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3769\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123651-300x225.jpg\" alt=\"20180908_123651\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123651-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123651-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123651.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123651-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123633.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3768\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123633-300x225.jpg\" alt=\"20180908_123633\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123633-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123633-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123633.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/10\/20180908_123633-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00d6STM\u00d6TE KARLSKRONA F\u00f6rsta stopp f\u00f6r denna dag blev p\u00e5 Marinmuseet i Karlskrona, d\u00e4r fick vi en intressant guide tur med Rolf och Rolf. Det blev en runda p\u00e5 ub\u00e5ts biten sedan lite historik om Karlskrona och marinen. Tror ni inte v\u00e5r egna president(Sandin) har haft tj\u00e4nsteg\u00f6rning p\u00e5 ub\u00e5ten Neptun eller var det Hajen Mmm.. lite [&hellip;]<\/p>\n","protected":false},"author":1640,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,2],"tags":[],"class_list":["post-3758","post","type-post","status-publish","format-standard","hentry","category-reportage","category-sydost"],"acf":[],"_links":{"self":[{"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/posts\/3758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/users\/1640"}],"replies":[{"embeddable":true,"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/comments?post=3758"}],"version-history":[{"count":2,"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/posts\/3758\/revisions"}],"predecessor-version":[{"id":3771,"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/posts\/3758\/revisions\/3771"}],"wp:attachment":[{"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/media?parent=3758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/categories?post=3758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/tags?post=3758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}