{"id":3498,"date":"2018-08-26T20:33:39","date_gmt":"2018-08-26T18:33:39","guid":{"rendered":"http:\/\/clubcorvette.se\/sydost\/?p=3498"},"modified":"2018-08-26T20:33:39","modified_gmt":"2018-08-26T18:33:39","slug":"pony-muscle-car-meet","status":"publish","type":"post","link":"https:\/\/clubcorvette.se\/sydost\/pony-muscle-car-meet\/","title":{"rendered":"Pony &amp; Muscle Car Meet"},"content":{"rendered":"<p><strong>Pony &amp; Muscle Car Meet den 4-5 Augusti<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Text och bild: Ingemo och Anders Sandin.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c4nnu en tr\u00e4ff med inriktning p\u00e5 massor av h\u00e4stkrafter i amerikanska bilar, narturligtvis var vi i corvetteclubben d\u00e4r.<\/p>\n<p>&nbsp;<\/p>\n<p>Den med gott minne kommer v\u00e4l ih\u00e5g attatt tr\u00e4ffen sp\u00e4nner sig \u00f6ver tv\u00e5 dagar.<\/p>\n<p>L\u00f6rdagen \u00e4r som de flesta biltr\u00e4ffar, en mix av mingel, olika t\u00e4vlingar stora som sm\u00e5 och prisutdelningar mm.<\/p>\n<p>&nbsp;<\/p>\n<p>En dag med bra v\u00e4der, fina bilar av olika m\u00e4rken, trevliga m\u00e4nniskor och ett antal av intressanta utst\u00e4llare att bes\u00f6ka \u00e4r aldrig fel. Kort sagt s\u00e5 blev det en lyckad dag.<\/p>\n<p>&nbsp;<\/p>\n<p>Tyv\u00e4rr s\u00e5 blev det lite smolk i b\u00e4garen f\u00f6r oss i CCS. H\u00f6r och h\u00e4pna ,vi fick inte n\u00e5got pris alls i de olika klasserna f\u00f6r finaste bil som delades ut.<\/p>\n<p>&nbsp;<\/p>\n<p>Trots allt s\u00e5 blev L\u00f6rdagen lyckad och S\u00f6ndagen stod f\u00f6r d\u00f6rren. En trevlig rallyrunda med fr\u00e5gor som tycktes tagna fr\u00e5n himmeln v\u00e4ntade oss. Nu lyckades det b\u00e4ttre eftersom Tony Holmqvist blev en av pristagarna.<\/p>\n<p>&nbsp;<\/p>\n<p>Nu \u00e5terstod bara tv\u00e5 saker, n\u00e4mligen att pricka in i almanackan n\u00e4r tr\u00e4ffen g\u00e5r av stapeln n\u00e4sta \u00e5r och s\u00e4ga hej och tack till de nyvunna v\u00e4nnerna.<\/p>\n<p><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051169.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3496\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051169-300x225.jpg\" alt=\"p8051169\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051169-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051169-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051169.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051169-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051153.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3481\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051153-300x225.jpg\" alt=\"p8051153\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051153-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051153-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051153.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051153-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041139.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3467\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041139-300x225.jpg\" alt=\"p8041139\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041139-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041139-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041139.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041139-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041135.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3464\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041135-300x225.jpg\" alt=\"p8041135\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041135-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041135-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041135.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041135-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041134.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3463\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041134-300x225.jpg\" alt=\"p8041134\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041134-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041134-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041134.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041134-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041132.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3461\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041132-300x225.jpg\" alt=\"p8041132\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041132-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041132-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041132.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041132-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051145.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3473\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051145-300x225.jpg\" alt=\"p8051145\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051145-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051145-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051145.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8051145-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041115.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3444\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041115-300x225.jpg\" alt=\"p8041115\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041115-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041115-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041115.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041115-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041127.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3456\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041127-300x225.jpg\" alt=\"p8041127\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041127-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041127-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041127.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041127-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041086.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3418\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041086-300x225.jpg\" alt=\"p8041086\" width=\"300\" height=\"225\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041082.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3414\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041082-300x225.jpg\" alt=\"p8041082\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041082-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041082-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041082.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041082-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041071.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3404\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041071-300x225.jpg\" alt=\"p8041071\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041071-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041071-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041071.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041071-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_203509.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3391\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_203509-225x300.jpg\" alt=\"20180804_203509\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_203509-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_203509.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_203509-480x640.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201132.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3390\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201132-300x225.jpg\" alt=\"20180804_201132\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201132-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201132-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201132.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201132-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201125.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3389\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201125-300x225.jpg\" alt=\"20180804_201125\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201125-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201125-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201125.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201125-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201113.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3388\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201113-225x300.jpg\" alt=\"20180804_201113\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201113-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201113.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201113-480x640.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201044.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3387\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201044-300x225.jpg\" alt=\"20180804_201044\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201044-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201044-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201044.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_201044-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_200438.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3382\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_200438-225x300.jpg\" alt=\"20180804_200438\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_200438-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_200438.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_200438-480x640.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122357.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3380\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122357-225x300.jpg\" alt=\"20180804_122357\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122357-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122357.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122357-480x640.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122347.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3379\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122347-225x300.jpg\" alt=\"20180804_122347\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122347-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122347.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122347-480x640.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122245.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3378\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122245-300x225.jpg\" alt=\"20180804_122245\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122245-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122245-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122245.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122245-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122043.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3375\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122043-225x300.jpg\" alt=\"20180804_122043\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122043-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122043.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_122043-480x640.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_120726.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3374\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_120726-225x300.jpg\" alt=\"20180804_120726\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_120726-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_120726.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_120726-480x640.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_115923.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3373\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_115923-225x300.jpg\" alt=\"20180804_115923\" width=\"225\" height=\"300\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_115923-225x300.jpg 225w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_115923.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/20180804_115923-480x640.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041063.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3397\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041063-300x225.jpg\" alt=\"p8041063\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041063-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041063-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041063.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041063-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041066.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3400\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041066-300x225.jpg\" alt=\"p8041066\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041066-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041066-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041066.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041066-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041074.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3406\" src=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041074-300x225.jpg\" alt=\"p8041074\" width=\"300\" height=\"225\" srcset=\"https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041074-300x225.jpg 300w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041074-768x576.jpg 768w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041074.jpg 1024w, https:\/\/clubcorvette.se\/sydost\/wp-content\/uploads\/sites\/8\/2018\/08\/P8041074-853x640.jpg 853w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pony &amp; Muscle Car Meet den 4-5 Augusti \u00a0 Text och bild: Ingemo och Anders Sandin. &nbsp; &nbsp; \u00c4nnu en tr\u00e4ff med inriktning p\u00e5 massor av h\u00e4stkrafter i amerikanska bilar, narturligtvis var vi i corvetteclubben d\u00e4r. &nbsp; Den med gott minne kommer v\u00e4l ih\u00e5g attatt tr\u00e4ffen sp\u00e4nner sig \u00f6ver tv\u00e5 dagar. L\u00f6rdagen \u00e4r som de [&hellip;]<\/p>\n","protected":false},"author":1640,"featured_media":3372,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,2],"tags":[],"class_list":["post-3498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reportage","category-sydost"],"acf":[],"_links":{"self":[{"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/posts\/3498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/users\/1640"}],"replies":[{"embeddable":true,"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/comments?post=3498"}],"version-history":[{"count":3,"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/posts\/3498\/revisions"}],"predecessor-version":[{"id":3501,"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/posts\/3498\/revisions\/3501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/media\/3372"}],"wp:attachment":[{"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/media?parent=3498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/categories?post=3498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clubcorvette.se\/sydost\/wp-json\/wp\/v2\/tags?post=3498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}